{"id":6408,"date":"2015-03-01T15:58:37","date_gmt":"2015-03-01T20:58:37","guid":{"rendered":"http:\/\/www.aikidocenterofjacksonville.com\/blog\/?p=6408"},"modified":"2015-03-01T15:58:37","modified_gmt":"2015-03-01T20:58:37","slug":"a-celebration-with-friends","status":"publish","type":"post","link":"https:\/\/www.aikidocenterofjacksonville.com\/blog\/2015\/03\/a-celebration-with-friends\/","title":{"rendered":"A Celebration with Friends"},"content":{"rendered":"<script>\/* <![CDATA[ *\/ portfolio_slideshow.slideshows[544] = {\"timeout\":\"4000\",\"autoplay\":\"false\",\"trans\":\"fade\",\"loop\":\"true\",\"speed\":\"400\",\"nowrap\":\"true\"}; \/* ]]> *\/<\/script><div id=\"slideshow-wrapper544\" class=\"slideshow-wrapper clearfix portfolio-slideshow-centered\">\n<div id=\"slideshow-nav544\" class=\"slideshow-nav\">\n\t<a class=\"pause\" style=\"display:none\" href=\"javascript:void(0);\">Pause<\/a>\n\t<a class=\"play\" href=\"javascript:void(0);\">Play<\/a>\n\t<a class=\"restart\" style=\"display:none\" href=\"javascript: void(0);\">Play<\/a>\n\t<a class=\"slideshow-prev\" href=\"javascript: void(0);\">Prev<\/a>\n\t<span class=\"sep\">|<\/span>\n\t<a class=\"slideshow-next\" href=\"javascript: void(0);\">Next<\/a>\n\t<span class=\"slideshow-info544 slideshow-info\"><\/span>\n<\/div><!-- .slideshow-nav -->\n<div id=\"portfolio-slideshow544\" class=\"portfolio-slideshow\" style=\"\">\n\n\t\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content \">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-content\/uploads\/2015\/03\/1-e1425243101640-300x225.jpg\" src=\"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-content\/uploads\/2015\/03\/1-e1425243101640-300x225.jpg\" height=\"225\" width=\"300\" alt=\"Slide 1\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-content\/uploads\/2015\/03\/2-300x164.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"164\" width=\"300\" alt=\"Slide 2\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-content\/uploads\/2015\/03\/3-300x206.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"206\" width=\"300\" alt=\"Slide 3\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-content\/uploads\/2015\/03\/4-300x165.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"165\" width=\"300\" alt=\"Slide 4\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-content\/uploads\/2015\/03\/5-278x300.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"300\" width=\"278\" alt=\"Slide 5\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-content\/uploads\/2015\/03\/6-300x179.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"179\" width=\"300\" alt=\"Slide 6\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-content\/uploads\/2015\/03\/7-300x184.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"184\" width=\"300\" alt=\"Slide 7\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-content\/uploads\/2015\/03\/8-300x196.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"196\" width=\"300\" alt=\"Slide 8\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-content\/uploads\/2015\/03\/9-300x188.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"188\" width=\"300\" alt=\"Slide 9\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-content\/uploads\/2015\/03\/10-300x200.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"200\" width=\"300\" alt=\"Slide 10\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-content\/uploads\/2015\/03\/11-300x190.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"190\" width=\"300\" alt=\"Slide 11\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-content\/uploads\/2015\/03\/12-300x177.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"177\" width=\"300\" alt=\"Slide 12\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-content\/uploads\/2015\/03\/13-269x300.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"300\" width=\"269\" alt=\"Slide 13\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-content\/uploads\/2015\/03\/14-300x175.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"175\" width=\"300\" alt=\"Slide 14\"><\/a>\t\t<\/div>\n\n\t<\/div>\n<div class=\"slideshow-meta\">\n\n\t\n\t\t\t<p class=\"slideshow-caption\">\n\t\t\t\t\t<\/p>\n\t\n\t\n\n\t\n\t\t\t<p class=\"slideshow-caption\">\n\t\t\t\t\t<\/p>\n\t\n\t\n\n\t\n\t\t\t<p class=\"slideshow-caption\">\n\t\t\t\t\t<\/p>\n\t\n\t\n\n\t\n\t\t\t<p class=\"slideshow-caption\">\n\t\t\t\t\t<\/p>\n\t\n\t\n\n\t\n\t\t\t<p class=\"slideshow-caption\">\n\t\t\t\t\t<\/p>\n\t\n\t\n\n\t\n\t\t\t<p class=\"slideshow-caption\">\n\t\t\t\t\t<\/p>\n\t\n\t\n\n\t\n\t\t\t<p class=\"slideshow-caption\">\n\t\t\t\t\t<\/p>\n\t\n\t\n\n\t\n\t\t\t<p class=\"slideshow-caption\">\n\t\t\t\t\t<\/p>\n\t\n\t\n\n\t\n\t\t\t<p class=\"slideshow-caption\">\n\t\t\t\t\t<\/p>\n\t\n\t\n\n\t\n\t\t\t<p class=\"slideshow-caption\">\n\t\t\t\t\t<\/p>\n\t\n\t\n\n\t\n\t\t\t<p class=\"slideshow-caption\">\n\t\t\t\t\t<\/p>\n\t\n\t\n\n\t\n\t\t\t<p class=\"slideshow-caption\">\n\t\t\t\t\t<\/p>\n\t\n\t\n\n\t\n\t\t\t<p class=\"slideshow-caption\">\n\t\t\t\t\t<\/p>\n\t\n\t\n\n\t\n\t\t\t<p class=\"slideshow-caption\">\n\t\t\t\t\t<\/p>\n\t\n\t\n<\/div><\/div><!--#slideshow-wrapper-->\n<p>Thank you again Lane Sensei for visiting us. Your presentation of Dee Sensei&#8217;s Shidoin certificate was a highlight for Dee personally, and for the school as well. Congratulations also to Kevin for passing his\u00a01st kyu test, and to Evan for passing 6th kyu. (And thank you Karen for your superlative ukemi during Kevin&#8217;s\u00a0test!)<\/p>\n<p>We had such a wonderful time practicing Aikido and spending the day with friends.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thank you again Lane Sensei for visiting us. Your presentation of Dee Sensei&#8217;s Shidoin certificate was a highlight for Dee personally, and for the school as well. Congratulations also to Kevin for passing his\u00a01st kyu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6414,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[26,6,44,25,28],"tags":[],"class_list":["post-6408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dojo","category-jerry","category-photos","category-sensei","category-testing"],"_links":{"self":[{"href":"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-json\/wp\/v2\/posts\/6408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-json\/wp\/v2\/comments?post=6408"}],"version-history":[{"count":2,"href":"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-json\/wp\/v2\/posts\/6408\/revisions"}],"predecessor-version":[{"id":6424,"href":"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-json\/wp\/v2\/posts\/6408\/revisions\/6424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-json\/wp\/v2\/media\/6414"}],"wp:attachment":[{"href":"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-json\/wp\/v2\/media?parent=6408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-json\/wp\/v2\/categories?post=6408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aikidocenterofjacksonville.com\/blog\/wp-json\/wp\/v2\/tags?post=6408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}